{"id":100333,"count":1,"description":"","link":"https:\/\/folhadoleste.com.br\/en\/tag\/divida-trabalhista\/","name":"d\u00edvida trabalhista","slug":"divida-trabalhista","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>d\u00edvida trabalhista &#8226; Folha do Leste<\/title>\n<meta name=\"description\" content=\"&#8226; Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadoleste.com.br\/en\/tag\/divida-trabalhista\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"d\u00edvida trabalhista &#8226; Folha do Leste\" \/>\n<meta property=\"og:description\" content=\"&#8226; Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadoleste.com.br\/en\/tag\/divida-trabalhista\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha do Leste\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FolhadoLesteRJ\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/tag\\\/divida-trabalhista\\\/\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/tag\\\/divida-trabalhista\\\/\",\"name\":\"d\u00edvida trabalhista &#8226; Folha do Leste\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#website\"},\"description\":\"&#8226; Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/tag\\\/divida-trabalhista\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/tag\\\/divida-trabalhista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"d\u00edvida trabalhista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#website\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/\",\"name\":\"Folha do Leste\",\"description\":\"Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama\",\"publisher\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\"},\"alternateName\":\"FL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhadoleste.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\",\"name\":\"Brasil 21 Comunica\u00e7\u00e3o\",\"alternateName\":\"BR21\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/brasil-21-logomarca.avif\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/brasil-21-logomarca.avif\",\"width\":1044,\"height\":1044,\"caption\":\"Brasil 21 Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/folhadoleste\",\"https:\\\/\\\/x.com\\\/FolhadoLesteRJ\",\"https:\\\/\\\/www.instagram.com\\\/folhadoleste\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"d\u00edvida trabalhista &#8226; Folha do Leste","description":"&#8226; Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadoleste.com.br\/en\/tag\/divida-trabalhista\/","og_locale":"en_US","og_type":"article","og_title":"d\u00edvida trabalhista &#8226; Folha do Leste","og_description":"&#8226; Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama","og_url":"https:\/\/folhadoleste.com.br\/en\/tag\/divida-trabalhista\/","og_site_name":"Folha do Leste","twitter_card":"summary_large_image","twitter_site":"@FolhadoLesteRJ","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/folhadoleste.com.br\/tag\/divida-trabalhista\/","url":"https:\/\/folhadoleste.com.br\/tag\/divida-trabalhista\/","name":"d\u00edvida trabalhista &#8226; Folha do Leste","isPartOf":{"@id":"https:\/\/folhadoleste.com.br\/#website"},"description":"&#8226; Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama","breadcrumb":{"@id":"https:\/\/folhadoleste.com.br\/tag\/divida-trabalhista\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/folhadoleste.com.br\/tag\/divida-trabalhista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadoleste.com.br\/"},{"@type":"ListItem","position":2,"name":"d\u00edvida trabalhista"}]},{"@type":"WebSite","@id":"https:\/\/folhadoleste.com.br\/#website","url":"https:\/\/folhadoleste.com.br\/","name":"Folha do Leste","description":"Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama","publisher":{"@id":"https:\/\/folhadoleste.com.br\/#organization"},"alternateName":"FL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadoleste.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/folhadoleste.com.br\/#organization","name":"Brasil 21 Comunica\u00e7\u00e3o","alternateName":"BR21","url":"https:\/\/folhadoleste.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/12\/brasil-21-logomarca.avif","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/12\/brasil-21-logomarca.avif","width":1044,"height":1044,"caption":"Brasil 21 Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/folhadoleste.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/folhadoleste","https:\/\/x.com\/FolhadoLesteRJ","https:\/\/www.instagram.com\/folhadoleste\/"]}]}},"_links":{"self":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/tags\/100333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts?tags=100333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}