{"id":171893,"date":"2026-05-13T18:02:04","date_gmt":"2026-05-13T21:02:04","guid":{"rendered":"https:\/\/folhadoleste.com.br\/?p=171893"},"modified":"2026-05-13T18:03:04","modified_gmt":"2026-05-13T21:03:04","slug":"subsidio-para-gasolina-e-diesel-governo-federal","status":"publish","type":"post","link":"https:\/\/folhadoleste.com.br\/en\/subsidio-para-gasolina-e-diesel-governo-federal\/","title":{"rendered":"Governo federal prev\u00ea subs\u00eddio para evitar disparada no pre\u00e7o da gasolina e do diesel"},"content":{"rendered":"<div id=\"attachment_171894\" style=\"width: 1290px\" class=\"wp-caption aligncenter\"><a class=\"link-image-noticia\" href=\"https:\/\/folhadoleste.com.br\/en\/subsidio-para-gasolina-e-diesel-governo-federal\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-171894\" class=\"&lt;a href=&quot;https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/&quot; rel=&quot;bookmark&quot; wp-image-171894 size-full\" title=\"Carro sendo abastecido de gasolina em um posto de combustivel\" src=\"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/subsidio-para-gasolina-e-diesel-governo-federal-divulgacao-agencia-senado.webp\" alt=\"Carro sendo abastecido de gasolina em um posto de combustivel\" width=\"1280\" height=\"720\" \/><\/a><p id=\"caption-attachment-171894\" class=\"wp-caption-text\">Governo federal prev\u00ea subs\u00eddio para evitar disparada no pre\u00e7o da gasolina e do diesel | Divulga\u00e7\u00e3o\/Ag\u00eancia Senado<\/p><\/div>\n<p style=\"text-align: justify;\">O governo do presidente Luiz In\u00e1cio Lula da Silva anunciou nesta quarta-feira (13) uma nova medida para reduzir os impactos da alta dos combust\u00edveis no pa\u00eds. A iniciativa prev\u00ea o pagamento de subs\u00eddios a produtores e importadores de gasolina e \u00f3leo diesel.<\/p>\n<p style=\"text-align: justify;\">Com a nova medida, o governo pretende evitar que a alta internacional do petr\u00f3leo, provocada pelas tens\u00f5es entre Israel, Estados Unidos e Ir\u00e3, seja integralmente repassada ao consumidor final.<\/p>\n<p style=\"text-align: justify;\">A \u00faltima altera\u00e7\u00e3o no pre\u00e7o da gasolina ocorreu em janeiro deste ano, quando a Petrobras reduziu em R$ 0,14 o valor m\u00e9dio do litro nas refinarias, que passou para R$ 2,57.<\/p>\n<p style=\"text-align: justify;\">Para viabilizar a medida, o governo federal editar\u00e1 uma Medida Provis\u00f3ria (MP). O an\u00fancio ocorre em meio \u00e0 expectativa de reajuste nos pre\u00e7os praticados pela Petrobras diante da guerra.<\/p>\n<h3 style=\"text-align: justify;\">Aumento do pre\u00e7o em breve<\/h3>\n<p style=\"text-align: justify;\">Durante teleconfer\u00eancia sobre os resultados do primeiro trimestre da estatal, a presidente da Petrobras, Magda Chambriard, afirmou que um reajuste da gasolina deve ocorrer em breve.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">\u201cN\u00f3s estamos tratando disso. Vai acontecer j\u00e1 j\u00e1 um aumento de pre\u00e7o da gasolina\u201d, declarou.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Segundo o ministro de Minas e Energia, Alexandre Silveira, a Uni\u00e3o ir\u00e1 compensar parte dos tributos federais pagos pelas empresas, como PIS\/Pasep, Cofins e Cide. A subven\u00e7\u00e3o poder\u00e1 chegar a at\u00e9 R$ 0,89 por litro de gasolina e R$ 0,35 por litro de diesel.<\/p>\n<div id=\"attachment_171895\" style=\"width: 1290px\" class=\"wp-caption aligncenter\"><a class=\"link-image-noticia\" href=\"https:\/\/folhadoleste.com.br\/en\/subsidio-para-gasolina-e-diesel-governo-federal\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-171895\" class=\"&lt;a href=&quot;https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/&quot; rel=&quot;bookmark&quot; wp-image-171895 size-full\" title=\"Subs\u00eddio para gasolina e diesel busca conter alta dos combust\u00edveis nos postos\" src=\"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/subsidio-para-gasolina-e-diesel-governo-federal-divulgacao-agencia-senado-2.webp\" alt=\"Subs\u00eddio para gasolina e diesel busca conter alta dos combust\u00edveis nos postos\" width=\"1280\" height=\"720\" \/><\/a><p id=\"caption-attachment-171895\" class=\"wp-caption-text\">Governo federal prev\u00ea subs\u00eddio para evitar disparada no pre\u00e7o da gasolina e do diesel | Divulga\u00e7\u00e3o\/Ag\u00eancia Senado<\/p><\/div>\n<p style=\"text-align: justify;\">De acordo com o ministro, a proposta inicial prev\u00ea um abatimento de R$ 0,40 por litro da gasolina. No caso do diesel, a tributa\u00e7\u00e3o federal j\u00e1 est\u00e1 zerada desde mar\u00e7o, por meio de uma medida tempor\u00e1ria que perde validade no fim de maio. A expectativa do governo \u00e9 ampliar posteriormente o benef\u00edcio tamb\u00e9m para o combust\u00edvel.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">\u201cEssa \u00e9 mais uma medida fundamental para minimizar os impactos na bomba de gasolina e diesel em todos os postos do Brasil\u201d, afirmou Alexandre Silveira.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Nesta quarta-feira, o barril do petr\u00f3leo tipo Brent, refer\u00eancia internacional, ultrapassou os US$ 100. Em fevereiro, a cota\u00e7\u00e3o estava abaixo de US$ 70.<\/p>\n<p style=\"text-align: justify;\">A implementa\u00e7\u00e3o do subs\u00eddio tamb\u00e9m ocorre em meio ao impasse sobre a vota\u00e7\u00e3o do Projeto de Lei Complementar (PLP) 114, que prev\u00ea o uso de receitas extras do petr\u00f3leo para reduzir impostos sobre combust\u00edveis. Apesar de ter tido o regime de urg\u00eancia aprovado, o texto ainda n\u00e3o avan\u00e7ou na C\u00e2mara dos Deputados.<\/p>\n<h5 style=\"text-align: center;\"><span style=\"color: #000000;\"><span style=\"color: #ff0000;\"><strong>+ <\/strong><\/span><\/span><span style=\"color: #000000;\"><strong><a href=\"https:\/\/folhadoleste.com.br\/en\/category\/brasil\/\"><span style=\"color: #ff9900;\">MAIS NOT\u00cdCIAS DO BRASIL<\/span><\/a><\/strong><\/span><\/h5>","protected":false},"excerpt":{"rendered":"<p>O governo do presidente Luiz In\u00e1cio Lula da Silva anunciou nesta quarta-feira (13) uma nova medida para reduzir os impactos da alta dos combust\u00edveis no pa\u00eds. A iniciativa prev\u00ea o pagamento de subs\u00eddios a produtores e importadores de gasolina e \u00f3leo diesel. Com a nova medida, o governo pretende evitar que a alta internacional do petr\u00f3leo, provocada pelas tens\u00f5es entre Israel, Estados Unidos e Ir\u00e3, seja integralmente repassada ao consumidor final. A \u00faltima altera\u00e7\u00e3o no pre\u00e7o da gasolina ocorreu em janeiro deste ano, quando a Petrobras reduziu em R$ 0,14 o valor m\u00e9dio do litro nas refinarias, que passou para [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":171894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[400,68,2965,398,397,1186,190877,395,1488,3786,190876],"class_list":["post-171893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-alexandre-silveira","tag-brasil","tag-combustiveis","tag-diesel","tag-gasolina","tag-governo-federal","tag-magda-chambriard","tag-petrobras","tag-petroleo","tag-preco-dos-combustiveis","tag-subsidio-para-gasolina-e-diesel","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo prev\u00ea subs\u00eddio para gasolina e diesel<\/title>\n<meta name=\"description\" content=\"Subs\u00eddio para gasolina e diesel busca conter alta dos combust\u00edveis diante da press\u00e3o internacional do petr\u00f3leo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadoleste.com.br\/en\/subsidio-para-gasolina-e-diesel-governo-federal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo prev\u00ea subs\u00eddio para gasolina e diesel\" \/>\n<meta property=\"og:description\" content=\"Subs\u00eddio para gasolina e diesel busca conter alta dos combust\u00edveis diante da press\u00e3o internacional do petr\u00f3leo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadoleste.com.br\/en\/subsidio-para-gasolina-e-diesel-governo-federal\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha do Leste\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/folhadoleste\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T21:02:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T21:03:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/subsidio-para-gasolina-e-diesel-governo-federal-divulgacao-agencia-senado.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Enzo Carvalho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FolhadoLesteRJ\" \/>\n<meta name=\"twitter:site\" content=\"@FolhadoLesteRJ\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enzo Carvalho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/subsidio-para-gasolina-e-diesel-governo-federal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/subsidio-para-gasolina-e-diesel-governo-federal\\\/\"},\"author\":{\"name\":\"Enzo Carvalho\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/person\\\/05d8a4b256c9faea581495e6c9be06f2\"},\"headline\":\"Governo federal prev\u00ea subs\u00eddio para evitar disparada no pre\u00e7o da gasolina e do diesel\",\"datePublished\":\"2026-05-13T21:02:04+00:00\",\"dateModified\":\"2026-05-13T21:03:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/subsidio-para-gasolina-e-diesel-governo-federal\\\/\"},\"wordCount\":480,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/subsidio-para-gasolina-e-diesel-governo-federal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/subsidio-para-gasolina-e-diesel-governo-federal-divulgacao-agencia-senado.webp\",\"keywords\":[\"Alexandre Silveira\",\"Brasil\",\"combust\u00edveis\",\"diesel\",\"gasolina\",\"Governo Federal\",\"Magda Chambriard\",\"Petrobras\",\"petr\u00f3leo\",\"pre\u00e7o dos combust\u00edveis\",\"subs\u00eddio para gasolina e diesel\"],\"articleSection\":[\"Brasil\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhadoleste.com.br\\\/subsidio-para-gasolina-e-diesel-governo-federal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/subsidio-para-gasolina-e-diesel-governo-federal\\\/\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/subsidio-para-gasolina-e-diesel-governo-federal\\\/\",\"name\":\"Governo prev\u00ea subs\u00eddio para gasolina e diesel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/subsidio-para-gasolina-e-diesel-governo-federal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/subsidio-para-gasolina-e-diesel-governo-federal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/subsidio-para-gasolina-e-diesel-governo-federal-divulgacao-agencia-senado.webp\",\"datePublished\":\"2026-05-13T21:02:04+00:00\",\"dateModified\":\"2026-05-13T21:03:04+00:00\",\"description\":\"Subs\u00eddio para gasolina e diesel busca conter alta dos combust\u00edveis diante da press\u00e3o internacional do petr\u00f3leo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/subsidio-para-gasolina-e-diesel-governo-federal\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhadoleste.com.br\\\/subsidio-para-gasolina-e-diesel-governo-federal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/subsidio-para-gasolina-e-diesel-governo-federal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/subsidio-para-gasolina-e-diesel-governo-federal-divulgacao-agencia-senado.webp\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/subsidio-para-gasolina-e-diesel-governo-federal-divulgacao-agencia-senado.webp\",\"width\":1280,\"height\":720,\"caption\":\"Governo federal prev\u00ea subs\u00eddio para evitar disparada no pre\u00e7o da gasolina e do diesel | Divulga\u00e7\u00e3o\\\/Ag\u00eancia Senado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/subsidio-para-gasolina-e-diesel-governo-federal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brasil\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/category\\\/brasil\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Governo federal prev\u00ea subs\u00eddio para evitar disparada no pre\u00e7o da gasolina e do diesel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#website\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/\",\"name\":\"Folha do Leste\",\"description\":\"Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama\",\"publisher\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\"},\"alternateName\":\"FL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhadoleste.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\",\"name\":\"Brasil 21 Comunica\u00e7\u00e3o\",\"alternateName\":\"BR21\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/brasil-21-logomarca.avif\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/brasil-21-logomarca.avif\",\"width\":1044,\"height\":1044,\"caption\":\"Brasil 21 Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/folhadoleste\",\"https:\\\/\\\/x.com\\\/FolhadoLesteRJ\",\"https:\\\/\\\/www.instagram.com\\\/folhadoleste\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/person\\\/05d8a4b256c9faea581495e6c9be06f2\",\"name\":\"Enzo Carvalho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761\",\"caption\":\"Enzo Carvalho\"},\"description\":\"Enzo Carvalho \u00e9 jornalista profissional, com atua\u00e7\u00e3o voltada \u00e0 cobertura de inova\u00e7\u00e3o, tecnologia, cotidiano e esportes. Ex-jogador profissional de e-sports, traz para o jornalismo uma compreens\u00e3o pr\u00e1tica do universo digital, das plataformas tecnol\u00f3gicas e das transforma\u00e7\u00f5es provocadas pela cultura conectada.\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/en\\\/author\\\/enzo-carvalho\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo prev\u00ea subs\u00eddio para gasolina e diesel","description":"Subs\u00eddio para gasolina e diesel busca conter alta dos combust\u00edveis diante da press\u00e3o internacional do petr\u00f3leo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadoleste.com.br\/en\/subsidio-para-gasolina-e-diesel-governo-federal\/","og_locale":"en_US","og_type":"article","og_title":"Governo prev\u00ea subs\u00eddio para gasolina e diesel","og_description":"Subs\u00eddio para gasolina e diesel busca conter alta dos combust\u00edveis diante da press\u00e3o internacional do petr\u00f3leo.","og_url":"https:\/\/folhadoleste.com.br\/en\/subsidio-para-gasolina-e-diesel-governo-federal\/","og_site_name":"Folha do Leste","article_publisher":"https:\/\/www.facebook.com\/folhadoleste","article_published_time":"2026-05-13T21:02:04+00:00","article_modified_time":"2026-05-13T21:03:04+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/subsidio-para-gasolina-e-diesel-governo-federal-divulgacao-agencia-senado.webp","type":"image\/webp"}],"author":"Enzo Carvalho","twitter_card":"summary_large_image","twitter_creator":"@FolhadoLesteRJ","twitter_site":"@FolhadoLesteRJ","twitter_misc":{"Written by":"Enzo Carvalho","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/#article","isPartOf":{"@id":"https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/"},"author":{"name":"Enzo Carvalho","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/person\/05d8a4b256c9faea581495e6c9be06f2"},"headline":"Governo federal prev\u00ea subs\u00eddio para evitar disparada no pre\u00e7o da gasolina e do diesel","datePublished":"2026-05-13T21:02:04+00:00","dateModified":"2026-05-13T21:03:04+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/"},"wordCount":480,"commentCount":0,"publisher":{"@id":"https:\/\/folhadoleste.com.br\/#organization"},"image":{"@id":"https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/subsidio-para-gasolina-e-diesel-governo-federal-divulgacao-agencia-senado.webp","keywords":["Alexandre Silveira","Brasil","combust\u00edveis","diesel","gasolina","Governo Federal","Magda Chambriard","Petrobras","petr\u00f3leo","pre\u00e7o dos combust\u00edveis","subs\u00eddio para gasolina e diesel"],"articleSection":["Brasil"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/","url":"https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/","name":"Governo prev\u00ea subs\u00eddio para gasolina e diesel","isPartOf":{"@id":"https:\/\/folhadoleste.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/#primaryimage"},"image":{"@id":"https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/subsidio-para-gasolina-e-diesel-governo-federal-divulgacao-agencia-senado.webp","datePublished":"2026-05-13T21:02:04+00:00","dateModified":"2026-05-13T21:03:04+00:00","description":"Subs\u00eddio para gasolina e diesel busca conter alta dos combust\u00edveis diante da press\u00e3o internacional do petr\u00f3leo.","breadcrumb":{"@id":"https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/#primaryimage","url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/subsidio-para-gasolina-e-diesel-governo-federal-divulgacao-agencia-senado.webp","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/subsidio-para-gasolina-e-diesel-governo-federal-divulgacao-agencia-senado.webp","width":1280,"height":720,"caption":"Governo federal prev\u00ea subs\u00eddio para evitar disparada no pre\u00e7o da gasolina e do diesel | Divulga\u00e7\u00e3o\/Ag\u00eancia Senado"},{"@type":"BreadcrumbList","@id":"https:\/\/folhadoleste.com.br\/subsidio-para-gasolina-e-diesel-governo-federal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadoleste.com.br\/"},{"@type":"ListItem","position":2,"name":"Brasil","item":"https:\/\/folhadoleste.com.br\/category\/brasil\/"},{"@type":"ListItem","position":3,"name":"Governo federal prev\u00ea subs\u00eddio para evitar disparada no pre\u00e7o da gasolina e do diesel"}]},{"@type":"WebSite","@id":"https:\/\/folhadoleste.com.br\/#website","url":"https:\/\/folhadoleste.com.br\/","name":"Folha do Leste","description":"Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama","publisher":{"@id":"https:\/\/folhadoleste.com.br\/#organization"},"alternateName":"FL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadoleste.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/folhadoleste.com.br\/#organization","name":"Brasil 21 Comunica\u00e7\u00e3o","alternateName":"BR21","url":"https:\/\/folhadoleste.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/12\/brasil-21-logomarca.avif","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/12\/brasil-21-logomarca.avif","width":1044,"height":1044,"caption":"Brasil 21 Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/folhadoleste.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/folhadoleste","https:\/\/x.com\/FolhadoLesteRJ","https:\/\/www.instagram.com\/folhadoleste\/"]},{"@type":"Person","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/person\/05d8a4b256c9faea581495e6c9be06f2","name":"Enzo Carvalho","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761","url":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761","caption":"Enzo Carvalho"},"description":"Enzo Carvalho \u00e9 jornalista profissional, com atua\u00e7\u00e3o voltada \u00e0 cobertura de inova\u00e7\u00e3o, tecnologia, cotidiano e esportes. Ex-jogador profissional de e-sports, traz para o jornalismo uma compreens\u00e3o pr\u00e1tica do universo digital, das plataformas tecnol\u00f3gicas e das transforma\u00e7\u00f5es provocadas pela cultura conectada.","url":"https:\/\/folhadoleste.com.br\/en\/author\/enzo-carvalho\/"}]}},"_links":{"self":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/171893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/comments?post=171893"}],"version-history":[{"count":3,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/171893\/revisions"}],"predecessor-version":[{"id":171898,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/171893\/revisions\/171898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/media\/171894"}],"wp:attachment":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/media?parent=171893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/categories?post=171893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/tags?post=171893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}