{"id":171860,"date":"2026-05-13T15:10:12","date_gmt":"2026-05-13T18:10:12","guid":{"rendered":"https:\/\/folhadoleste.com.br\/?p=171860"},"modified":"2026-05-13T15:11:47","modified_gmt":"2026-05-13T18:11:47","slug":"castillo-no-fluminense-corte-perna-operario-copa-do-brasil","status":"publish","type":"post","link":"https:\/\/folhadoleste.com.br\/en\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/","title":{"rendered":"Castillo sofre corte na perna e pode desfalcar o Fluminense"},"content":{"rendered":"<div id=\"attachment_171861\" style=\"width: 1290px\" class=\"wp-caption aligncenter\"><a class=\"link-image-noticia\" href=\"https:\/\/folhadoleste.com.br\/en\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-171861\" class=\"&lt;a href=&quot;https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/&quot; rel=&quot;bookmark&quot; wp-image-171861 size-full\" title=\"Castillo no Fluminense sofre corte na perna direita durante jogo contra o Oper\u00e1rio-PR\" src=\"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil-marcelo-goncalves-fluminense.webp\" alt=\"Castillo no Fluminense sofre corte na perna direita durante jogo contra o Oper\u00e1rio-PR\" width=\"1280\" height=\"720\" \/><\/a><p id=\"caption-attachment-171861\" class=\"wp-caption-text\">Castillo sofre corte na perna e pode desfalcar o Fluminense | Marcelo Gon\u00e7alves\/Fluminense<\/p><\/div>\n<p style=\"text-align: justify;\" data-start=\"637\" data-end=\"928\"><strong data-start=\"637\" data-end=\"663\">Castillo no Fluminense<\/strong> virou <strong>motivo<\/strong> de <strong>preocupa\u00e7\u00e3o<\/strong> ap\u00f3s a <strong>classifica\u00e7\u00e3o tricolor<\/strong> na <strong>Copa do Brasil.<\/strong> O <strong>atacante sofreu<\/strong> um <strong>corte<\/strong> na <strong>perna direita<\/strong> durante a <a href=\"https:\/\/folhadoleste.com.br\/en\/fluminense-vence-operario-copa-do-brasil-oitavas\/\"><strong>vit\u00f3ria<\/strong> por <strong>2 a 1<\/strong> sobre o <\/a><strong><a href=\"https:\/\/folhadoleste.com.br\/en\/fluminense-vence-operario-copa-do-brasil-oitavas\/\">Oper\u00e1rio-PR<\/a>,<\/strong> na \u00faltima <strong>ter\u00e7a-feira (12),<\/strong> no <strong>Maracan\u00e3,<\/strong> e pode virar <strong>desfalque<\/strong> para a <strong>sequ\u00eancia<\/strong> da <strong>temporada.<\/strong><\/p>\n<p style=\"text-align: justify;\" data-start=\"930\" data-end=\"1139\">O lance aconteceu j\u00e1 nos acr\u00e9scimos da partida de volta da quinta fase. Com o resultado, o Fluminense avan\u00e7ou \u00e0s oitavas de final do torneio nacional, mas terminou o jogo atento \u00e0 situa\u00e7\u00e3o f\u00edsica do argentino.<\/p>\n<h2 data-section-id=\"1ufzbq6\" data-start=\"1141\" data-end=\"1177\">Atacante levou a pior em dividida<\/h2>\n<p style=\"text-align: justify;\" data-start=\"1179\" data-end=\"1323\">Castillo se antecipou a Pedro Vilhena e conseguiu tirar a bola. No entanto, o jogador do Oper\u00e1rio chegou atrasado e acertou o atacante em cheio.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1325\" data-end=\"1522\">Na sequ\u00eancia, Pedro Vilhena arrastou a sola da chuteira da canela \u00e0 coxa do centroavante. O corte exigiu atendimento m\u00e9dico ainda no gramado, enquanto jogadores do Fluminense reclamavam da entrada.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1524\" data-end=\"1632\">Apesar da for\u00e7a do lance, o \u00e1rbitro Jo\u00e3o Vitor Gobi aplicou apenas cart\u00e3o amarelo ao jogador do Oper\u00e1rio-PR.<\/p>\n<h3 data-section-id=\"rkjxnf\" data-start=\"1634\" data-end=\"1666\">Castillo reclamou ap\u00f3s o jogo<\/h3>\n<p style=\"text-align: justify;\" data-start=\"1668\" data-end=\"1838\">Ao fim da partida, Castillo foi at\u00e9 o \u00e1rbitro para mostrar o ferimento e reclamar da decis\u00e3o de campo. O argentino demonstrou indigna\u00e7\u00e3o com a n\u00e3o expuls\u00e3o do advers\u00e1rio.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1840\" data-end=\"2023\">A reclama\u00e7\u00e3o ocorreu depois de um jogo tenso nos minutos finais. O Oper\u00e1rio havia descontado no placar e tentava pressionar em busca do empate, que levaria a decis\u00e3o para os p\u00eanaltis.<\/p>\n<p style=\"text-align: justify;\" data-start=\"2025\" data-end=\"2229\">Pouco depois do gol paranaense, Edwin Torres acabou expulso por receber o segundo cart\u00e3o amarelo. Ainda assim, o lance em Castillo ficou como uma das principais queixas do Fluminense ap\u00f3s a classifica\u00e7\u00e3o.<\/p>\n<h3 data-section-id=\"s436uw\" data-start=\"2231\" data-end=\"2272\">Situa\u00e7\u00e3o ser\u00e1 avaliada pelo Fluminense<\/h3>\n<p style=\"text-align: justify;\" data-start=\"2274\" data-end=\"2507\">O Fluminense ainda deve avaliar a gravidade do corte na perna direita do atacante. A preocupa\u00e7\u00e3o envolve n\u00e3o apenas o ferimento, mas tamb\u00e9m o risco de dor, limita\u00e7\u00e3o nos movimentos e necessidade de cuidados m\u00e9dicos nos pr\u00f3ximos dias.<\/p>\n<p style=\"text-align: justify;\" data-start=\"2509\" data-end=\"2701\">Por isso, Castillo pode virar d\u00favida para o pr\u00f3ximo compromisso tricolor. A comiss\u00e3o t\u00e9cnica deve acompanhar a evolu\u00e7\u00e3o do jogador antes de definir se ele ter\u00e1 condi\u00e7\u00f5es de ficar \u00e0 disposi\u00e7\u00e3o.<\/p>\n<h3 data-section-id=\"1qam3jo\" data-start=\"2703\" data-end=\"2747\">Tricolor volta a campo contra o S\u00e3o Paulo<\/h3>\n<p style=\"text-align: justify;\" data-start=\"2749\" data-end=\"2906\">O pr\u00f3ximo jogo do Fluminense ser\u00e1 contra o S\u00e3o Paulo, no s\u00e1bado (16), \u00e0s 19h, novamente no Maracan\u00e3. A partida vale pela 16\u00aa rodada do Campeonato Brasileiro.<\/p>\n<p style=\"text-align: justify;\" data-start=\"2908\" data-end=\"3113\">Depois de garantir vaga nas oitavas da Copa do Brasil, o Tricolor vira a chave para o Brasileir\u00e3o. No entanto, a poss\u00edvel aus\u00eancia de Castillo pode reduzir as op\u00e7\u00f5es ofensivas de Zubeld\u00eda para o confronto.<\/p>\n<h4 style=\"text-align: justify;\" data-section-id=\"1moxkbm\" data-start=\"3115\" data-end=\"3154\">Classifica\u00e7\u00e3o veio com alerta f\u00edsico<\/h4>\n<p style=\"text-align: justify;\" data-start=\"3156\" data-end=\"3393\">A vit\u00f3ria sobre o Oper\u00e1rio-PR confirmou o favoritismo do Fluminense, que havia empatado por 0 a 0 no jogo de ida, em Ponta Grossa. Savarino e Lucho Acosta marcaram os gols tricolores, enquanto Felipe Augusto descontou para os visitantes.<\/p>\n<p style=\"text-align: justify;\" data-start=\"3395\" data-end=\"3599\">Mesmo com a classifica\u00e7\u00e3o, o corte sofrido por Castillo deixou um alerta no elenco. Agora, o clube precisa aguardar a resposta m\u00e9dica para saber se o atacante seguir\u00e1 dispon\u00edvel na sequ\u00eancia da temporada.<\/p>\n<h5 style=\"text-align: center;\"><span style=\"color: #000000;\"><span style=\"color: #ff0000;\"><strong>+ <\/strong><\/span><\/span><span style=\"color: #000000;\"><strong><a href=\"https:\/\/folhadoleste.com.br\/en\/category\/esportes\/\"><span style=\"color: #ff9900;\">MAIS NOT\u00cdCIAS DE ESPORTES<\/span><\/a><\/strong><\/span><\/h5>","protected":false},"excerpt":{"rendered":"<p>Castillo no Fluminense virou motivo de preocupa\u00e7\u00e3o ap\u00f3s a classifica\u00e7\u00e3o tricolor na Copa do Brasil. O atacante sofreu um corte na perna direita durante a vit\u00f3ria por 2 a 1 sobre o Oper\u00e1rio-PR, na \u00faltima ter\u00e7a-feira (12), no Maracan\u00e3, e pode virar desfalque para a sequ\u00eancia da temporada. O lance aconteceu j\u00e1 nos acr\u00e9scimos da partida de volta da quinta fase. Com o resultado, o Fluminense avan\u00e7ou \u00e0s oitavas de final do torneio nacional, mas terminou o jogo atento \u00e0 situa\u00e7\u00e3o f\u00edsica do argentino. Atacante levou a pior em dividida Castillo se antecipou a Pedro Vilhena e conseguiu tirar a [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":171861,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,65],"tags":[2339,172019,190868,548,105,124,101,88087,286,190552,190869,735],"class_list":["post-171860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-futebol-esportes","tag-campeonato-brasileiro","tag-castillo","tag-castillo-no-fluminense","tag-copa-do-brasil","tag-esportes","tag-fluminense","tag-futebol","tag-joao-vitor-gobi","tag-maracana","tag-operario-pr","tag-pedro-vilhena","tag-sao-paulo","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Castillo sofre corte e pode desfalcar o Fluminense<\/title>\n<meta name=\"description\" content=\"Castillo no Fluminense virou preocupa\u00e7\u00e3o ap\u00f3s corte na perna direita durante vit\u00f3ria sobre o Oper\u00e1rio pela Copa do Brasil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadoleste.com.br\/en\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Castillo sofre corte e pode desfalcar o Fluminense\" \/>\n<meta property=\"og:description\" content=\"Castillo no Fluminense virou preocupa\u00e7\u00e3o ap\u00f3s corte na perna direita durante vit\u00f3ria sobre o Oper\u00e1rio pela Copa do Brasil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadoleste.com.br\/en\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha do Leste\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/folhadoleste\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T18:10:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T18:11:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil-marcelo-goncalves-fluminense.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Enzo Carvalho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FolhadoLesteRJ\" \/>\n<meta name=\"twitter:site\" content=\"@FolhadoLesteRJ\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enzo Carvalho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\\\/\"},\"author\":{\"name\":\"Enzo Carvalho\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/person\\\/05d8a4b256c9faea581495e6c9be06f2\"},\"headline\":\"Castillo sofre corte na perna e pode desfalcar o Fluminense\",\"datePublished\":\"2026-05-13T18:10:12+00:00\",\"dateModified\":\"2026-05-13T18:11:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\\\/\"},\"wordCount\":569,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil-marcelo-goncalves-fluminense.webp\",\"keywords\":[\"Campeonato Brasileiro\",\"Castillo\",\"Castillo no Fluminense\",\"Copa do Brasil\",\"Esportes\",\"fluminense\",\"futebol\",\"Jo\u00e3o Vitor Gobi\",\"Maracan\u00e3\",\"Oper\u00e1rio-PR\",\"Pedro Vilhena\",\"S\u00e3o Paulo\"],\"articleSection\":[\"Esportes\",\"Futebol\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhadoleste.com.br\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\\\/\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\\\/\",\"name\":\"Castillo sofre corte e pode desfalcar o Fluminense\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil-marcelo-goncalves-fluminense.webp\",\"datePublished\":\"2026-05-13T18:10:12+00:00\",\"dateModified\":\"2026-05-13T18:11:47+00:00\",\"description\":\"Castillo no Fluminense virou preocupa\u00e7\u00e3o ap\u00f3s corte na perna direita durante vit\u00f3ria sobre o Oper\u00e1rio pela Copa do Brasil.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhadoleste.com.br\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil-marcelo-goncalves-fluminense.webp\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil-marcelo-goncalves-fluminense.webp\",\"width\":1280,\"height\":720,\"caption\":\"Castillo sofre corte na perna e pode desfalcar o Fluminense | Marcelo Gon\u00e7alves\\\/Fluminense\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esportes\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/category\\\/esportes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Futebol\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/category\\\/esportes\\\/futebol-esportes\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Castillo sofre corte na perna e pode desfalcar o Fluminense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#website\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/\",\"name\":\"Folha do Leste\",\"description\":\"Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama\",\"publisher\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\"},\"alternateName\":\"FL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhadoleste.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\",\"name\":\"Brasil 21 Comunica\u00e7\u00e3o\",\"alternateName\":\"BR21\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/brasil-21-logomarca.avif\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/brasil-21-logomarca.avif\",\"width\":1044,\"height\":1044,\"caption\":\"Brasil 21 Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/folhadoleste\",\"https:\\\/\\\/x.com\\\/FolhadoLesteRJ\",\"https:\\\/\\\/www.instagram.com\\\/folhadoleste\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/person\\\/05d8a4b256c9faea581495e6c9be06f2\",\"name\":\"Enzo Carvalho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761\",\"caption\":\"Enzo Carvalho\"},\"description\":\"Enzo Carvalho \u00e9 jornalista profissional, com atua\u00e7\u00e3o voltada \u00e0 cobertura de inova\u00e7\u00e3o, tecnologia, cotidiano e esportes. Ex-jogador profissional de e-sports, traz para o jornalismo uma compreens\u00e3o pr\u00e1tica do universo digital, das plataformas tecnol\u00f3gicas e das transforma\u00e7\u00f5es provocadas pela cultura conectada.\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/en\\\/author\\\/enzo-carvalho\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Castillo sofre corte e pode desfalcar o Fluminense","description":"Castillo no Fluminense virou preocupa\u00e7\u00e3o ap\u00f3s corte na perna direita durante vit\u00f3ria sobre o Oper\u00e1rio pela Copa do Brasil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadoleste.com.br\/en\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/","og_locale":"en_US","og_type":"article","og_title":"Castillo sofre corte e pode desfalcar o Fluminense","og_description":"Castillo no Fluminense virou preocupa\u00e7\u00e3o ap\u00f3s corte na perna direita durante vit\u00f3ria sobre o Oper\u00e1rio pela Copa do Brasil.","og_url":"https:\/\/folhadoleste.com.br\/en\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/","og_site_name":"Folha do Leste","article_publisher":"https:\/\/www.facebook.com\/folhadoleste","article_published_time":"2026-05-13T18:10:12+00:00","article_modified_time":"2026-05-13T18:11:47+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil-marcelo-goncalves-fluminense.webp","type":"image\/webp"}],"author":"Enzo Carvalho","twitter_card":"summary_large_image","twitter_creator":"@FolhadoLesteRJ","twitter_site":"@FolhadoLesteRJ","twitter_misc":{"Written by":"Enzo Carvalho","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/#article","isPartOf":{"@id":"https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/"},"author":{"name":"Enzo Carvalho","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/person\/05d8a4b256c9faea581495e6c9be06f2"},"headline":"Castillo sofre corte na perna e pode desfalcar o Fluminense","datePublished":"2026-05-13T18:10:12+00:00","dateModified":"2026-05-13T18:11:47+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/"},"wordCount":569,"commentCount":0,"publisher":{"@id":"https:\/\/folhadoleste.com.br\/#organization"},"image":{"@id":"https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil-marcelo-goncalves-fluminense.webp","keywords":["Campeonato Brasileiro","Castillo","Castillo no Fluminense","Copa do Brasil","Esportes","fluminense","futebol","Jo\u00e3o Vitor Gobi","Maracan\u00e3","Oper\u00e1rio-PR","Pedro Vilhena","S\u00e3o Paulo"],"articleSection":["Esportes","Futebol"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/","url":"https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/","name":"Castillo sofre corte e pode desfalcar o Fluminense","isPartOf":{"@id":"https:\/\/folhadoleste.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/#primaryimage"},"image":{"@id":"https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil-marcelo-goncalves-fluminense.webp","datePublished":"2026-05-13T18:10:12+00:00","dateModified":"2026-05-13T18:11:47+00:00","description":"Castillo no Fluminense virou preocupa\u00e7\u00e3o ap\u00f3s corte na perna direita durante vit\u00f3ria sobre o Oper\u00e1rio pela Copa do Brasil.","breadcrumb":{"@id":"https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/#primaryimage","url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil-marcelo-goncalves-fluminense.webp","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil-marcelo-goncalves-fluminense.webp","width":1280,"height":720,"caption":"Castillo sofre corte na perna e pode desfalcar o Fluminense | Marcelo Gon\u00e7alves\/Fluminense"},{"@type":"BreadcrumbList","@id":"https:\/\/folhadoleste.com.br\/castillo-no-fluminense-corte-perna-operario-copa-do-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadoleste.com.br\/"},{"@type":"ListItem","position":2,"name":"Esportes","item":"https:\/\/folhadoleste.com.br\/category\/esportes\/"},{"@type":"ListItem","position":3,"name":"Futebol","item":"https:\/\/folhadoleste.com.br\/category\/esportes\/futebol-esportes\/"},{"@type":"ListItem","position":4,"name":"Castillo sofre corte na perna e pode desfalcar o Fluminense"}]},{"@type":"WebSite","@id":"https:\/\/folhadoleste.com.br\/#website","url":"https:\/\/folhadoleste.com.br\/","name":"Folha do Leste","description":"Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama","publisher":{"@id":"https:\/\/folhadoleste.com.br\/#organization"},"alternateName":"FL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadoleste.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/folhadoleste.com.br\/#organization","name":"Brasil 21 Comunica\u00e7\u00e3o","alternateName":"BR21","url":"https:\/\/folhadoleste.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/12\/brasil-21-logomarca.avif","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/12\/brasil-21-logomarca.avif","width":1044,"height":1044,"caption":"Brasil 21 Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/folhadoleste.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/folhadoleste","https:\/\/x.com\/FolhadoLesteRJ","https:\/\/www.instagram.com\/folhadoleste\/"]},{"@type":"Person","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/person\/05d8a4b256c9faea581495e6c9be06f2","name":"Enzo Carvalho","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761","url":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761","caption":"Enzo Carvalho"},"description":"Enzo Carvalho \u00e9 jornalista profissional, com atua\u00e7\u00e3o voltada \u00e0 cobertura de inova\u00e7\u00e3o, tecnologia, cotidiano e esportes. Ex-jogador profissional de e-sports, traz para o jornalismo uma compreens\u00e3o pr\u00e1tica do universo digital, das plataformas tecnol\u00f3gicas e das transforma\u00e7\u00f5es provocadas pela cultura conectada.","url":"https:\/\/folhadoleste.com.br\/en\/author\/enzo-carvalho\/"}]}},"_links":{"self":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/171860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/comments?post=171860"}],"version-history":[{"count":3,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/171860\/revisions"}],"predecessor-version":[{"id":171864,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/171860\/revisions\/171864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/media\/171861"}],"wp:attachment":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/media?parent=171860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/categories?post=171860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/tags?post=171860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}