{"id":171597,"date":"2026-05-11T10:35:27","date_gmt":"2026-05-11T13:35:27","guid":{"rendered":"https:\/\/folhadoleste.com.br\/?p=171597"},"modified":"2026-05-11T10:35:50","modified_gmt":"2026-05-11T13:35:50","slug":"acidente-na-br-040-em-petropolis-motociclista-morre","status":"publish","type":"post","link":"https:\/\/folhadoleste.com.br\/en\/acidente-na-br-040-em-petropolis-motociclista-morre\/","title":{"rendered":"Motociclista morre em acidente na BR-040 em Petr\u00f3polis"},"content":{"rendered":"<div id=\"attachment_171598\" style=\"width: 1290px\" class=\"wp-caption aligncenter\"><a class=\"link-image-noticia\" href=\"https:\/\/folhadoleste.com.br\/en\/acidente-na-br-040-em-petropolis-motociclista-morre\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-171598\" class=\"&lt;a href=https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/&quot; rel=&quot;bookmark&quot; wp-image-171598 size-full\" title=\"Acidente na BR-040 em Petr\u00f3polis deixa motociclista morto na entrada do bairro Rocio\" src=\"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/acidente-na-br-040-em-petropolis-motociclista-morre-reproducao.webp\" alt=\"Acidente na BR-040 em Petr\u00f3polis deixa motociclista morto na entrada do bairro Rocio\" width=\"1280\" height=\"720\" \/><\/a><p id=\"caption-attachment-171598\" class=\"wp-caption-text\">Motociclista morre em acidente na BR-040 em Petr\u00f3polis | Reprodu\u00e7\u00e3o<\/p><\/div>\n<p style=\"text-align: justify;\" data-start=\"617\" data-end=\"861\">Um <strong data-start=\"620\" data-end=\"656\">acidente na BR-040 em Petr\u00f3polis<\/strong> deixou um <strong>motociclista morto<\/strong> na <strong>manh\u00e3<\/strong> do \u00faltimo <strong>domingo (10),<\/strong> na <strong>Regi\u00e3o Serrana<\/strong> do <strong>Rio de Janeiro.<\/strong> A <strong>colis\u00e3o<\/strong> envolveu uma <strong>moto<\/strong> e um <strong>carro<\/strong> na entrada do <strong>bairro Rocio,<\/strong> segundo informa\u00e7\u00f5es do Corpo de Bombeiros.<\/p>\n<p style=\"text-align: justify;\" data-start=\"863\" data-end=\"1042\">A v\u00edtima conduzia a motocicleta e morreu ainda no local. At\u00e9 a \u00faltima atualiza\u00e7\u00e3o desta reportagem, a identidade e a idade do motociclista n\u00e3o haviam sido divulgadas oficialmente.<\/p>\n<h2 data-section-id=\"nd65s3\" data-start=\"1044\" data-end=\"1084\">Corpo de Bombeiros atendeu ocorr\u00eancia<\/h2>\n<p style=\"text-align: justify;\" data-start=\"1086\" data-end=\"1285\">O Corpo de Bombeiros informou que o chamado para a ocorr\u00eancia foi registrado por volta das 10h44. Depois do acionamento, equipes de socorro seguiram para o trecho da rodovia onde aconteceu a colis\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Apesar da chegada do atendimento, o motociclista n\u00e3o resistiu aos ferimentos. N\u00e3o havia, at\u00e9 o momento, confirma\u00e7\u00e3o sobre outros feridos nem informa\u00e7\u00f5es oficiais sobre o estado de sa\u00fade do motorista do carro.<\/p>\n<h3 data-section-id=\"27d034\" data-start=\"1497\" data-end=\"1537\">Imagens mostram carro parado na pista<\/h3>\n<p style=\"text-align: justify;\" data-start=\"1539\" data-end=\"1736\">Al\u00e9m disso, v\u00eddeos e imagens divulgados nas redes sociais mostram o carro envolvido no acidente parado na pista ap\u00f3s a batida. As circunst\u00e2ncias da colis\u00e3o, por\u00e9m, ainda n\u00e3o foram detalhadas pelas autoridades.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1738\" data-end=\"1906\">Por isso, ainda n\u00e3o h\u00e1 confirma\u00e7\u00e3o sobre a din\u00e2mica do acidente. Tamb\u00e9m n\u00e3o foi informado se houve interdi\u00e7\u00e3o total ou parcial da rodovia no trecho da entrada do Rocio.<\/p>\n<h4 style=\"text-align: justify;\" data-section-id=\"1l9rn5m\" data-start=\"1908\" data-end=\"1932\">Causas ser\u00e3o apuradas<\/h4>\n<p style=\"text-align: justify;\" data-start=\"1934\" data-end=\"2121\">Enfim, as causas do acidente dever\u00e3o ser investigadas pelas autoridades respons\u00e1veis. Assim, a apura\u00e7\u00e3o deve considerar a din\u00e2mica da colis\u00e3o, as condi\u00e7\u00f5es da via e os relatos de poss\u00edveis testemunhas.<\/p>\n<p style=\"text-align: justify;\" data-start=\"2123\" data-end=\"2257\">At\u00e9 a \u00faltima atualiza\u00e7\u00e3o, n\u00e3o havia detalhes sobre eventual registro em delegacia, per\u00edcia no local ou identifica\u00e7\u00e3o formal da v\u00edtima.<\/p>\n<h5 style=\"text-align: center;\"><span style=\"color: #000000;\"><span style=\"color: #ff0000;\"><strong>+ <\/strong><\/span><\/span><span style=\"color: #000000;\"><strong><a href=\"https:\/\/folhadoleste.com.br\/en\/category\/estado-do-rio-de-janeiro\/\"><span style=\"color: #ff9900;\">MAIS NOT\u00cdCIAS DO ESTADO DO RIO DE JANEIRO<\/span><\/a><\/strong><\/span><\/h5>","protected":false},"excerpt":{"rendered":"<p>Um acidente na BR-040 em Petr\u00f3polis deixou um motociclista morto na manh\u00e3 do \u00faltimo domingo (10), na Regi\u00e3o Serrana do Rio de Janeiro. A colis\u00e3o envolveu uma moto e um carro na entrada do bairro Rocio, segundo informa\u00e7\u00f5es do Corpo de Bombeiros. A v\u00edtima conduzia a motocicleta e morreu ainda no local. At\u00e9 a \u00faltima atualiza\u00e7\u00e3o desta reportagem, a identidade e a idade do motociclista n\u00e3o haviam sido divulgadas oficialmente. Corpo de Bombeiros atendeu ocorr\u00eancia O Corpo de Bombeiros informou que o chamado para a ocorr\u00eancia foi registrado por volta das 10h44. Depois do acionamento, equipes de socorro seguiram para [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":171598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,381],"tags":[45918,12492,190769,3620,3924,600,19484,3312,5813,190770,730],"class_list":["post-171597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado-do-rio-de-janeiro","category-regiao-serrana","tag-acidente-com-carro","tag-acidente-de-moto","tag-acidente-na-br-040-em-petropolis","tag-br-040","tag-corpo-de-bombeiros","tag-estado-do-rio","tag-motociclista-morto","tag-petropolis","tag-regiao-serrana","tag-rocio","tag-transito","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Motociclista morre em acidente na BR-040 em Petr\u00f3polis<\/title>\n<meta name=\"description\" content=\"Acidente na BR-040 em Petr\u00f3polis deixou um motociclista morto na manh\u00e3 deste domingo, na entrada do bairro Rocio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadoleste.com.br\/en\/acidente-na-br-040-em-petropolis-motociclista-morre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Motociclista morre em acidente na BR-040 em Petr\u00f3polis\" \/>\n<meta property=\"og:description\" content=\"Acidente na BR-040 em Petr\u00f3polis deixou um motociclista morto na manh\u00e3 deste domingo, na entrada do bairro Rocio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadoleste.com.br\/en\/acidente-na-br-040-em-petropolis-motociclista-morre\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha do Leste\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/folhadoleste\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T13:35:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T13:35:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/acidente-na-br-040-em-petropolis-motociclista-morre-reproducao.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Enzo Carvalho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FolhadoLesteRJ\" \/>\n<meta name=\"twitter:site\" content=\"@FolhadoLesteRJ\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enzo Carvalho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/acidente-na-br-040-em-petropolis-motociclista-morre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/acidente-na-br-040-em-petropolis-motociclista-morre\\\/\"},\"author\":{\"name\":\"Enzo Carvalho\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/person\\\/05d8a4b256c9faea581495e6c9be06f2\"},\"headline\":\"Motociclista morre em acidente na BR-040 em Petr\u00f3polis\",\"datePublished\":\"2026-05-11T13:35:27+00:00\",\"dateModified\":\"2026-05-11T13:35:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/acidente-na-br-040-em-petropolis-motociclista-morre\\\/\"},\"wordCount\":336,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/acidente-na-br-040-em-petropolis-motociclista-morre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/acidente-na-br-040-em-petropolis-motociclista-morre-reproducao.webp\",\"keywords\":[\"acidente com carro\",\"acidente de moto\",\"acidente na BR-040 em Petr\u00f3polis\",\"BR-040\",\"Corpo de Bombeiros\",\"estado do rio\",\"Motociclista Morto\",\"Petr\u00f3polis\",\"Regi\u00e3o Serrana\",\"Rocio\",\"Tr\u00e2nsito\"],\"articleSection\":[\"Estado do Rio de Janeiro\",\"Regi\u00e3o Serrana\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhadoleste.com.br\\\/acidente-na-br-040-em-petropolis-motociclista-morre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/acidente-na-br-040-em-petropolis-motociclista-morre\\\/\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/acidente-na-br-040-em-petropolis-motociclista-morre\\\/\",\"name\":\"Motociclista morre em acidente na BR-040 em Petr\u00f3polis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/acidente-na-br-040-em-petropolis-motociclista-morre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/acidente-na-br-040-em-petropolis-motociclista-morre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/acidente-na-br-040-em-petropolis-motociclista-morre-reproducao.webp\",\"datePublished\":\"2026-05-11T13:35:27+00:00\",\"dateModified\":\"2026-05-11T13:35:50+00:00\",\"description\":\"Acidente na BR-040 em Petr\u00f3polis deixou um motociclista morto na manh\u00e3 deste domingo, na entrada do bairro Rocio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/acidente-na-br-040-em-petropolis-motociclista-morre\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhadoleste.com.br\\\/acidente-na-br-040-em-petropolis-motociclista-morre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/acidente-na-br-040-em-petropolis-motociclista-morre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/acidente-na-br-040-em-petropolis-motociclista-morre-reproducao.webp\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/acidente-na-br-040-em-petropolis-motociclista-morre-reproducao.webp\",\"width\":1280,\"height\":720,\"caption\":\"Motociclista morre em acidente na BR-040 em Petr\u00f3polis | Reprodu\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/acidente-na-br-040-em-petropolis-motociclista-morre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regi\u00e3o Serrana\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/category\\\/regiao-serrana\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Motociclista morre em acidente na BR-040 em Petr\u00f3polis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#website\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/\",\"name\":\"Folha do Leste\",\"description\":\"Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama\",\"publisher\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\"},\"alternateName\":\"FL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhadoleste.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\",\"name\":\"Brasil 21 Comunica\u00e7\u00e3o\",\"alternateName\":\"BR21\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/brasil-21-logomarca.avif\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/brasil-21-logomarca.avif\",\"width\":1044,\"height\":1044,\"caption\":\"Brasil 21 Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/folhadoleste\",\"https:\\\/\\\/x.com\\\/FolhadoLesteRJ\",\"https:\\\/\\\/www.instagram.com\\\/folhadoleste\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/person\\\/05d8a4b256c9faea581495e6c9be06f2\",\"name\":\"Enzo Carvalho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761\",\"caption\":\"Enzo Carvalho\"},\"description\":\"Enzo Carvalho \u00e9 jornalista profissional, com atua\u00e7\u00e3o voltada \u00e0 cobertura de inova\u00e7\u00e3o, tecnologia, cotidiano e esportes. Ex-jogador profissional de e-sports, traz para o jornalismo uma compreens\u00e3o pr\u00e1tica do universo digital, das plataformas tecnol\u00f3gicas e das transforma\u00e7\u00f5es provocadas pela cultura conectada.\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/en\\\/author\\\/enzo-carvalho\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Motociclista morre em acidente na BR-040 em Petr\u00f3polis","description":"Acidente na BR-040 em Petr\u00f3polis deixou um motociclista morto na manh\u00e3 deste domingo, na entrada do bairro Rocio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadoleste.com.br\/en\/acidente-na-br-040-em-petropolis-motociclista-morre\/","og_locale":"en_US","og_type":"article","og_title":"Motociclista morre em acidente na BR-040 em Petr\u00f3polis","og_description":"Acidente na BR-040 em Petr\u00f3polis deixou um motociclista morto na manh\u00e3 deste domingo, na entrada do bairro Rocio.","og_url":"https:\/\/folhadoleste.com.br\/en\/acidente-na-br-040-em-petropolis-motociclista-morre\/","og_site_name":"Folha do Leste","article_publisher":"https:\/\/www.facebook.com\/folhadoleste","article_published_time":"2026-05-11T13:35:27+00:00","article_modified_time":"2026-05-11T13:35:50+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/acidente-na-br-040-em-petropolis-motociclista-morre-reproducao.webp","type":"image\/webp"}],"author":"Enzo Carvalho","twitter_card":"summary_large_image","twitter_creator":"@FolhadoLesteRJ","twitter_site":"@FolhadoLesteRJ","twitter_misc":{"Written by":"Enzo Carvalho","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/#article","isPartOf":{"@id":"https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/"},"author":{"name":"Enzo Carvalho","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/person\/05d8a4b256c9faea581495e6c9be06f2"},"headline":"Motociclista morre em acidente na BR-040 em Petr\u00f3polis","datePublished":"2026-05-11T13:35:27+00:00","dateModified":"2026-05-11T13:35:50+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/"},"wordCount":336,"commentCount":0,"publisher":{"@id":"https:\/\/folhadoleste.com.br\/#organization"},"image":{"@id":"https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/acidente-na-br-040-em-petropolis-motociclista-morre-reproducao.webp","keywords":["acidente com carro","acidente de moto","acidente na BR-040 em Petr\u00f3polis","BR-040","Corpo de Bombeiros","estado do rio","Motociclista Morto","Petr\u00f3polis","Regi\u00e3o Serrana","Rocio","Tr\u00e2nsito"],"articleSection":["Estado do Rio de Janeiro","Regi\u00e3o Serrana"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/","url":"https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/","name":"Motociclista morre em acidente na BR-040 em Petr\u00f3polis","isPartOf":{"@id":"https:\/\/folhadoleste.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/#primaryimage"},"image":{"@id":"https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/acidente-na-br-040-em-petropolis-motociclista-morre-reproducao.webp","datePublished":"2026-05-11T13:35:27+00:00","dateModified":"2026-05-11T13:35:50+00:00","description":"Acidente na BR-040 em Petr\u00f3polis deixou um motociclista morto na manh\u00e3 deste domingo, na entrada do bairro Rocio.","breadcrumb":{"@id":"https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/#primaryimage","url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/acidente-na-br-040-em-petropolis-motociclista-morre-reproducao.webp","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/05\/acidente-na-br-040-em-petropolis-motociclista-morre-reproducao.webp","width":1280,"height":720,"caption":"Motociclista morre em acidente na BR-040 em Petr\u00f3polis | Reprodu\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/folhadoleste.com.br\/acidente-na-br-040-em-petropolis-motociclista-morre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadoleste.com.br\/"},{"@type":"ListItem","position":2,"name":"Regi\u00e3o Serrana","item":"https:\/\/folhadoleste.com.br\/category\/regiao-serrana\/"},{"@type":"ListItem","position":3,"name":"Motociclista morre em acidente na BR-040 em Petr\u00f3polis"}]},{"@type":"WebSite","@id":"https:\/\/folhadoleste.com.br\/#website","url":"https:\/\/folhadoleste.com.br\/","name":"Folha do Leste","description":"Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama","publisher":{"@id":"https:\/\/folhadoleste.com.br\/#organization"},"alternateName":"FL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadoleste.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/folhadoleste.com.br\/#organization","name":"Brasil 21 Comunica\u00e7\u00e3o","alternateName":"BR21","url":"https:\/\/folhadoleste.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/12\/brasil-21-logomarca.avif","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/12\/brasil-21-logomarca.avif","width":1044,"height":1044,"caption":"Brasil 21 Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/folhadoleste.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/folhadoleste","https:\/\/x.com\/FolhadoLesteRJ","https:\/\/www.instagram.com\/folhadoleste\/"]},{"@type":"Person","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/person\/05d8a4b256c9faea581495e6c9be06f2","name":"Enzo Carvalho","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761","url":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761","caption":"Enzo Carvalho"},"description":"Enzo Carvalho \u00e9 jornalista profissional, com atua\u00e7\u00e3o voltada \u00e0 cobertura de inova\u00e7\u00e3o, tecnologia, cotidiano e esportes. Ex-jogador profissional de e-sports, traz para o jornalismo uma compreens\u00e3o pr\u00e1tica do universo digital, das plataformas tecnol\u00f3gicas e das transforma\u00e7\u00f5es provocadas pela cultura conectada.","url":"https:\/\/folhadoleste.com.br\/en\/author\/enzo-carvalho\/"}]}},"_links":{"self":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/171597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/comments?post=171597"}],"version-history":[{"count":2,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/171597\/revisions"}],"predecessor-version":[{"id":171600,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/171597\/revisions\/171600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/media\/171598"}],"wp:attachment":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/media?parent=171597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/categories?post=171597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/tags?post=171597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}