{"id":167714,"date":"2026-03-25T23:41:52","date_gmt":"2026-03-26T02:41:52","guid":{"rendered":"https:\/\/folhadoleste.com.br\/?p=167714"},"modified":"2026-03-26T21:39:24","modified_gmt":"2026-03-27T00:39:24","slug":"camboinhas-recebe-a-corrida-e-caminhada-do-coracao","status":"publish","type":"post","link":"https:\/\/folhadoleste.com.br\/en\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/","title":{"rendered":"Camboinhas recebe a Corrida e Caminhada do Cora\u00e7\u00e3o"},"content":{"rendered":"<div id=\"attachment_167724\" style=\"width: 1290px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-167724\" class=\"wp-image-167724 size-full\" src=\"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/03\/Camboinhas-recebe-Corrida-e-Caminhada-do-CoracaoDivulgacao.webp.jpg\" alt=\"Corrida e Caminhada do Cora\u00e7\u00e3o acontece no dia 12 de abril em Camboinhas. Foto: Divulga\u00e7\u00e3o.\" width=\"1280\" height=\"720\" \/><p id=\"caption-attachment-167724\" class=\"wp-caption-text\">Corrida e Caminhada do Cora\u00e7\u00e3o acontece no dia 12 de abril em Camboinhas. Foto: Divulga\u00e7\u00e3o.<\/p><\/div>\n<p style=\"text-align: justify;\">Quem curte esportes e natureza pode reservar o dia 12 de abril para juntar ambas as paix\u00f5es. Isso porque o bairro de Camboinhas, na Regi\u00e3o Oce\u00e2nica, recebe a Corrida e Caminhada do Cora\u00e7\u00e3o. O evento chega \u00e0 6\u00aa edi\u00e7\u00e3o em 2026. O in\u00edcio do trajeto ser\u00e1 no estacionamento do TioSam.<\/p>\n<p style=\"text-align: justify;\">Com percursos de 5 e 10 km para a corrida e 2,5km para quem for caminhar, o evento tem o objetivo de destacar a sa\u00fade, preven\u00e7\u00e3o e a qualidade de vida. Ou seja, uma experi\u00eancia para quem deseja se movimentar, cuidar do cora\u00e7\u00e3o e celebrar h\u00e1bitos saud\u00e1veis. Al\u00e9m disso, haver\u00e1<span style=\"font-size: 1.21429rem;\"> aferi\u00e7\u00e3o de press\u00e3o e glicose. A largada dos 10km ser\u00e1 a partir de 7 horas.\u00a0 \u00c0s 7h15 acontece a dos 5km e \u00e0s 7h30 ser\u00e1 a aminhada de 2,5km.<\/span><\/p>\n<p style=\"text-align: justify;\">Organizador da prova, Fabr\u00edcio Narcimento afirma que outro objetivo \u00e9 incentivar a pr\u00e1tica esportiva di\u00e1ria. Al\u00e9m disso, explicouo como o evento pode influenciar algu\u00e9m a ter h\u00e1bitos saud\u00e1veis.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">O evento tem como principal objetivo incentivar a pr\u00e1tica de atividade f\u00edsica e conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia da preven\u00e7\u00e3o das doen\u00e7as, principalmente as cardiovasculares. Ele foi idealizado pelo Centro de Exerc\u00edcios Seacor, que tem foco em reabilita\u00e7\u00e3o card\u00edaca. A ideia \u00e9 estimular a pr\u00e1tica de atividade f\u00edsica e incentivar um estilo de vida saud\u00e1vel. O nome do evento refor\u00e7a essa mensagem de cuidado e preven\u00e7\u00e3o&#8221;, disse Fabr\u00edcio Nascimento, organizador da prova.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Quem tiver interesse em participar, pode ser inscrever no <a href=\"https:\/\/site.ticketsports.com.br\/Inscricao\/categoria.aspx?__idEvento=85408&amp;lang=pt-PT\">site oficial da Corrida e Caminhada do Cora\u00e7\u00e3o<\/a>.<\/p>\n<p style=\"text-align: justify;\">A 6\u00aa edi\u00e7\u00e3o da Corrida e Caminhada do Cora\u00e7\u00e3o tem os patroc\u00ednios do Centro de Exerc\u00edcios Seacor, do Niter\u00f3i D\u00b4Or Hospital, Morales Laborat\u00f3rio, A\u00e7oGym Academia Gratuita,\u00a0 \u00c1gua mineral L\u00b4\u00c1qua, Pai&amp;Filhos Mudan\u00e7as, Nutren Senior, BYD | Dinisa, CONVIVA Engenharia, Drogarias Tamoio e Apsen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Quem curte esportes e natureza pode reservar o dia 12 de abril para juntar ambas as paix\u00f5es. Isso porque o bairro de Camboinhas, na Regi\u00e3o Oce\u00e2nica, recebe a Corrida e Caminhada do Cora\u00e7\u00e3o. O evento chega \u00e0 6\u00aa edi\u00e7\u00e3o em 2026. O in\u00edcio do trajeto ser\u00e1 no estacionamento do TioSam. Com percursos de 5 e 10 km para a corrida e 2,5km para quem for caminhar, o evento tem o objetivo de destacar a sa\u00fade, preven\u00e7\u00e3o e a qualidade de vida. Ou seja, uma experi\u00eancia para quem deseja se movimentar, cuidar do cora\u00e7\u00e3o e celebrar h\u00e1bitos saud\u00e1veis. Al\u00e9m disso, haver\u00e1 [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":167724,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[513,5],"tags":[4096,5049,190144,190146,189281,50,806,190145],"class_list":["post-167714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano","category-noticias-de-niteroi","tag-afericao-de-pressao-arterial","tag-camboinhas","tag-corrida-e-caminhada-do-coracao","tag-lestefluminense","tag-medicao-de-glicose","tag-niteroi","tag-regiao-oceanica","tag-tiosam","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Camboinhas recebe a Corrida e Caminhada do Cora\u00e7\u00e3o &#8226; Folha do Leste<\/title>\n<meta name=\"description\" content=\"Isso porque o bairro de Camboinhas, na Regi\u00e3o Oce\u00e2nica, recebe a Corrida e Caminhada do Cora\u00e7\u00e3o. O evento chega \u00e0 6\u00aa edi\u00e7\u00e3o em 2026.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadoleste.com.br\/en\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camboinhas recebe a Corrida e Caminhada do Cora\u00e7\u00e3o &#8226; Folha do Leste\" \/>\n<meta property=\"og:description\" content=\"Isso porque o bairro de Camboinhas, na Regi\u00e3o Oce\u00e2nica, recebe a Corrida e Caminhada do Cora\u00e7\u00e3o. O evento chega \u00e0 6\u00aa edi\u00e7\u00e3o em 2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadoleste.com.br\/en\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha do Leste\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/folhadoleste\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T02:41:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T00:39:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/03\/Camboinhas-recebe-Corrida-e-Caminhada-do-CoracaoDivulgacao.webp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriel Gontijo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FolhadoLesteRJ\" \/>\n<meta name=\"twitter:site\" content=\"@FolhadoLesteRJ\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Gontijo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\\\/\"},\"author\":{\"name\":\"Gabriel Gontijo\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/person\\\/b221dfcb2145a1f2b2629b441b0a1270\"},\"headline\":\"Camboinhas recebe a Corrida e Caminhada do Cora\u00e7\u00e3o\",\"datePublished\":\"2026-03-26T02:41:52+00:00\",\"dateModified\":\"2026-03-27T00:39:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\\\/\"},\"wordCount\":360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Camboinhas-recebe-Corrida-e-Caminhada-do-CoracaoDivulgacao.webp.jpg\",\"keywords\":[\"aferi\u00e7\u00e3o de press\u00e3o arterial\",\"camboinhas\",\"Corrida e Caminhada do Cora\u00e7\u00e3o\",\"LesteFluminense\",\"medi\u00e7\u00e3o de glicose\",\"Niter\u00f3i\",\"Regi\u00e3o Oce\u00e2nica\",\"TioSam\"],\"articleSection\":[\"Cotidiano\",\"Niter\u00f3i\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhadoleste.com.br\\\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\\\/\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\\\/\",\"name\":\"Camboinhas recebe a Corrida e Caminhada do Cora\u00e7\u00e3o &#8226; Folha do Leste\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Camboinhas-recebe-Corrida-e-Caminhada-do-CoracaoDivulgacao.webp.jpg\",\"datePublished\":\"2026-03-26T02:41:52+00:00\",\"dateModified\":\"2026-03-27T00:39:24+00:00\",\"description\":\"Isso porque o bairro de Camboinhas, na Regi\u00e3o Oce\u00e2nica, recebe a Corrida e Caminhada do Cora\u00e7\u00e3o. O evento chega \u00e0 6\u00aa edi\u00e7\u00e3o em 2026.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhadoleste.com.br\\\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Camboinhas-recebe-Corrida-e-Caminhada-do-CoracaoDivulgacao.webp.jpg\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Camboinhas-recebe-Corrida-e-Caminhada-do-CoracaoDivulgacao.webp.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Corrida e Caminhada do Cora\u00e7\u00e3o acontece no dia 12 de abril em Camboinhas. Foto: Divulga\u00e7\u00e3o.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estado do Rio de Janeiro\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/category\\\/estado-do-rio-de-janeiro\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Leste Fluminense\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/category\\\/estado-do-rio-de-janeiro\\\/leste-fluminense\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Niter\u00f3i\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/category\\\/estado-do-rio-de-janeiro\\\/leste-fluminense\\\/noticias-de-niteroi\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Camboinhas recebe a Corrida e Caminhada do Cora\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#website\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/\",\"name\":\"Folha do Leste\",\"description\":\"Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama\",\"publisher\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\"},\"alternateName\":\"FL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhadoleste.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\",\"name\":\"Brasil 21 Comunica\u00e7\u00e3o\",\"alternateName\":\"BR21\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/brasil-21-logomarca.avif\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/brasil-21-logomarca.avif\",\"width\":1044,\"height\":1044,\"caption\":\"Brasil 21 Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/folhadoleste\",\"https:\\\/\\\/x.com\\\/FolhadoLesteRJ\",\"https:\\\/\\\/www.instagram.com\\\/folhadoleste\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/person\\\/b221dfcb2145a1f2b2629b441b0a1270\",\"name\":\"Gabriel Gontijo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/ec69cbfd472624d176510944f17f9555.jpg?ver=1778371110\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/ec69cbfd472624d176510944f17f9555.jpg?ver=1778371110\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/ec69cbfd472624d176510944f17f9555.jpg?ver=1778371110\",\"caption\":\"Gabriel Gontijo\"},\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/en\\\/author\\\/gabriel-gontijo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camboinhas recebe a Corrida e Caminhada do Cora\u00e7\u00e3o &#8226; Folha do Leste","description":"Isso porque o bairro de Camboinhas, na Regi\u00e3o Oce\u00e2nica, recebe a Corrida e Caminhada do Cora\u00e7\u00e3o. O evento chega \u00e0 6\u00aa edi\u00e7\u00e3o em 2026.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadoleste.com.br\/en\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/","og_locale":"en_US","og_type":"article","og_title":"Camboinhas recebe a Corrida e Caminhada do Cora\u00e7\u00e3o &#8226; Folha do Leste","og_description":"Isso porque o bairro de Camboinhas, na Regi\u00e3o Oce\u00e2nica, recebe a Corrida e Caminhada do Cora\u00e7\u00e3o. O evento chega \u00e0 6\u00aa edi\u00e7\u00e3o em 2026.","og_url":"https:\/\/folhadoleste.com.br\/en\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/","og_site_name":"Folha do Leste","article_publisher":"https:\/\/www.facebook.com\/folhadoleste","article_published_time":"2026-03-26T02:41:52+00:00","article_modified_time":"2026-03-27T00:39:24+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/03\/Camboinhas-recebe-Corrida-e-Caminhada-do-CoracaoDivulgacao.webp.jpg","type":"image\/jpeg"}],"author":"Gabriel Gontijo","twitter_card":"summary_large_image","twitter_creator":"@FolhadoLesteRJ","twitter_site":"@FolhadoLesteRJ","twitter_misc":{"Written by":"Gabriel Gontijo","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/folhadoleste.com.br\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/#article","isPartOf":{"@id":"https:\/\/folhadoleste.com.br\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/"},"author":{"name":"Gabriel Gontijo","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/person\/b221dfcb2145a1f2b2629b441b0a1270"},"headline":"Camboinhas recebe a Corrida e Caminhada do Cora\u00e7\u00e3o","datePublished":"2026-03-26T02:41:52+00:00","dateModified":"2026-03-27T00:39:24+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadoleste.com.br\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/"},"wordCount":360,"commentCount":0,"publisher":{"@id":"https:\/\/folhadoleste.com.br\/#organization"},"image":{"@id":"https:\/\/folhadoleste.com.br\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/03\/Camboinhas-recebe-Corrida-e-Caminhada-do-CoracaoDivulgacao.webp.jpg","keywords":["aferi\u00e7\u00e3o de press\u00e3o arterial","camboinhas","Corrida e Caminhada do Cora\u00e7\u00e3o","LesteFluminense","medi\u00e7\u00e3o de glicose","Niter\u00f3i","Regi\u00e3o Oce\u00e2nica","TioSam"],"articleSection":["Cotidiano","Niter\u00f3i"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadoleste.com.br\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadoleste.com.br\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/","url":"https:\/\/folhadoleste.com.br\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/","name":"Camboinhas recebe a Corrida e Caminhada do Cora\u00e7\u00e3o &#8226; Folha do Leste","isPartOf":{"@id":"https:\/\/folhadoleste.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadoleste.com.br\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/#primaryimage"},"image":{"@id":"https:\/\/folhadoleste.com.br\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/03\/Camboinhas-recebe-Corrida-e-Caminhada-do-CoracaoDivulgacao.webp.jpg","datePublished":"2026-03-26T02:41:52+00:00","dateModified":"2026-03-27T00:39:24+00:00","description":"Isso porque o bairro de Camboinhas, na Regi\u00e3o Oce\u00e2nica, recebe a Corrida e Caminhada do Cora\u00e7\u00e3o. O evento chega \u00e0 6\u00aa edi\u00e7\u00e3o em 2026.","breadcrumb":{"@id":"https:\/\/folhadoleste.com.br\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadoleste.com.br\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/#primaryimage","url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/03\/Camboinhas-recebe-Corrida-e-Caminhada-do-CoracaoDivulgacao.webp.jpg","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2026\/03\/Camboinhas-recebe-Corrida-e-Caminhada-do-CoracaoDivulgacao.webp.jpg","width":1280,"height":720,"caption":"Corrida e Caminhada do Cora\u00e7\u00e3o acontece no dia 12 de abril em Camboinhas. Foto: Divulga\u00e7\u00e3o."},{"@type":"BreadcrumbList","@id":"https:\/\/folhadoleste.com.br\/camboinhas-recebe-a-corrida-e-caminhada-do-coracao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadoleste.com.br\/"},{"@type":"ListItem","position":2,"name":"Estado do Rio de Janeiro","item":"https:\/\/folhadoleste.com.br\/category\/estado-do-rio-de-janeiro\/"},{"@type":"ListItem","position":3,"name":"Leste Fluminense","item":"https:\/\/folhadoleste.com.br\/category\/estado-do-rio-de-janeiro\/leste-fluminense\/"},{"@type":"ListItem","position":4,"name":"Niter\u00f3i","item":"https:\/\/folhadoleste.com.br\/category\/estado-do-rio-de-janeiro\/leste-fluminense\/noticias-de-niteroi\/"},{"@type":"ListItem","position":5,"name":"Camboinhas recebe a Corrida e Caminhada do Cora\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/folhadoleste.com.br\/#website","url":"https:\/\/folhadoleste.com.br\/","name":"Folha do Leste","description":"Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama","publisher":{"@id":"https:\/\/folhadoleste.com.br\/#organization"},"alternateName":"FL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadoleste.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/folhadoleste.com.br\/#organization","name":"Brasil 21 Comunica\u00e7\u00e3o","alternateName":"BR21","url":"https:\/\/folhadoleste.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/12\/brasil-21-logomarca.avif","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/12\/brasil-21-logomarca.avif","width":1044,"height":1044,"caption":"Brasil 21 Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/folhadoleste.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/folhadoleste","https:\/\/x.com\/FolhadoLesteRJ","https:\/\/www.instagram.com\/folhadoleste\/"]},{"@type":"Person","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/person\/b221dfcb2145a1f2b2629b441b0a1270","name":"Gabriel Gontijo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/ec69cbfd472624d176510944f17f9555.jpg?ver=1778371110","url":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/ec69cbfd472624d176510944f17f9555.jpg?ver=1778371110","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/ec69cbfd472624d176510944f17f9555.jpg?ver=1778371110","caption":"Gabriel Gontijo"},"url":"https:\/\/folhadoleste.com.br\/en\/author\/gabriel-gontijo\/"}]}},"_links":{"self":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/167714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/comments?post=167714"}],"version-history":[{"count":2,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/167714\/revisions"}],"predecessor-version":[{"id":167889,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/167714\/revisions\/167889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/media\/167724"}],"wp:attachment":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/media?parent=167714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/categories?post=167714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/tags?post=167714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}