{"id":140313,"date":"2025-09-18T17:51:59","date_gmt":"2025-09-18T20:51:59","guid":{"rendered":"https:\/\/folhadoleste.com.br\/?p=140313"},"modified":"2025-09-18T17:51:59","modified_gmt":"2025-09-18T20:51:59","slug":"ceara-proibe-ultraprocessados-merenda-escolar","status":"publish","type":"post","link":"https:\/\/folhadoleste.com.br\/en\/ceara-proibe-ultraprocessados-merenda-escolar\/","title":{"rendered":"Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027"},"content":{"rendered":"<div id=\"attachment_140314\" style=\"width: 1180px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-140314\" class=\"size-full wp-image-140314\" src=\"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/09\/Ceara-veta-alimentos-ultraprocessados-na-merenda-escolar-ate-2027-Foto-Antonio-Cruz-AGencia-Brasil.webp\" alt=\"\" width=\"1170\" height=\"700\" \/><p id=\"caption-attachment-140314\" class=\"wp-caption-text\">Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027 | Antonio Cruz\/Ag\u00eancia Brasil<\/p><\/div>\n<p style=\"text-align: justify;\" data-start=\"196\" data-end=\"419\">A <strong data-start=\"198\" data-end=\"260\">proibi\u00e7\u00e3o de alimentos ultraprocessados na merenda escolar<\/strong> foi sancionada nesta quinta-feira (18) pelo governador do Cear\u00e1, <strong data-start=\"326\" data-end=\"347\">Eumano de Freitas<\/strong>. A medida alcan\u00e7a todas as escolas p\u00fablicas e particulares do estado.<\/p>\n<h3 style=\"text-align: justify;\" data-start=\"421\" data-end=\"466\">Transi\u00e7\u00e3o gradual at\u00e9 a elimina\u00e7\u00e3o total<\/h3>\n<p style=\"text-align: justify;\" data-start=\"467\" data-end=\"688\">De acordo com a nova lei, a retirada ser\u00e1 feita por etapas. Em <strong data-start=\"530\" data-end=\"538\">2026<\/strong>, os ultraprocessados s\u00f3 poder\u00e3o representar at\u00e9 <strong data-start=\"587\" data-end=\"594\">10%<\/strong> das refei\u00e7\u00f5es. J\u00e1 em <strong data-start=\"616\" data-end=\"624\">2027<\/strong>, eles ser\u00e3o completamente eliminados dos card\u00e1pios escolares.<\/p>\n<p style=\"text-align: justify;\" data-start=\"690\" data-end=\"1208\">A assinatura ocorreu durante a abertura da <strong data-start=\"733\" data-end=\"792\">2\u00aa C\u00fapula da Coaliza\u00e7\u00e3o Global para Alimenta\u00e7\u00e3o Escolar<\/strong>, realizada em Fortaleza, com a presen\u00e7a de representantes de mais de 80 pa\u00edses.<\/p>\n<p style=\"text-align: justify;\" data-start=\"690\" data-end=\"1208\">O ato contou ainda com o ministro da Educa\u00e7\u00e3o, <strong data-start=\"920\" data-end=\"938\">Camilo Santana<\/strong>, e a diretora executiva do <strong data-start=\"966\" data-end=\"999\">Programa Mundial de Alimentos<\/strong>, <strong data-start=\"1001\" data-end=\"1017\">Cindy McCain<\/strong>, que tamb\u00e9m assinaram simbolicamente o documento.<\/p>\n<p style=\"text-align: justify;\" data-start=\"690\" data-end=\"1208\">O vice-presidente <strong data-start=\"1086\" data-end=\"1105\">Geraldo Alckmin<\/strong> participou do evento e elogiou a iniciativa, sem confirmar se a medida ser\u00e1 estendida nacionalmente.<\/p>\n<h3 style=\"text-align: justify;\" data-start=\"1210\" data-end=\"1232\">Contexto nacional<\/h3>\n<p style=\"text-align: justify;\" data-start=\"1233\" data-end=\"1453\">O <strong data-start=\"1235\" data-end=\"1254\">governo federal<\/strong> j\u00e1 havia reduzido o limite de alimentos processados e ultraprocessados no <strong data-start=\"1329\" data-end=\"1380\">Programa Nacional de Alimenta\u00e7\u00e3o Escolar (PNAE)<\/strong>. Em 2025, esse percentual ser\u00e1 de <strong data-start=\"1415\" data-end=\"1422\">15%<\/strong>, chegando a <strong data-start=\"1435\" data-end=\"1450\">10% em 2026<\/strong>.<\/p>\n<p style=\"text-align: justify;\" data-start=\"1455\" data-end=\"1635\">O PNAE atende <strong data-start=\"1469\" data-end=\"1497\">40 milh\u00f5es de estudantes<\/strong> em <strong data-start=\"1501\" data-end=\"1520\">150 mil escolas<\/strong> de todo o pa\u00eds, servindo <strong data-start=\"1546\" data-end=\"1581\">50 milh\u00f5es de refei\u00e7\u00f5es di\u00e1rias<\/strong>. O custo anual do programa \u00e9 de <strong data-start=\"1614\" data-end=\"1632\">R$ 5,5 bilh\u00f5es<\/strong>.<\/p>\n<pre style=\"text-align: center;\"><span style=\"color: #000000;\"><span style=\"color: #ff0000;\"><strong>+ <\/strong><\/span><\/span><span style=\"color: #000000;\"><strong><span style=\"color: #ff9900;\">MAIS NOT\u00cdCIAS DO BRASIL?<\/span> <span style=\"color: #008080;\"><a style=\"color: #008080;\" href=\"https:\/\/folhadoleste.com.br\/en\/category\/brasil\/\">CLIQUE AQUI<\/a><\/span><\/strong><\/span><\/pre>","protected":false},"excerpt":{"rendered":"<p>A proibi\u00e7\u00e3o de alimentos ultraprocessados na merenda escolar foi sancionada nesta quinta-feira (18) pelo governador do Cear\u00e1, Eumano de Freitas. A medida alcan\u00e7a todas as escolas p\u00fablicas e particulares do estado. Transi\u00e7\u00e3o gradual at\u00e9 a elimina\u00e7\u00e3o total De acordo com a nova lei, a retirada ser\u00e1 feita por etapas. Em 2026, os ultraprocessados s\u00f3 poder\u00e3o representar at\u00e9 10% das refei\u00e7\u00f5es. J\u00e1 em 2027, eles ser\u00e3o completamente eliminados dos card\u00e1pios escolares. A assinatura ocorreu durante a abertura da 2\u00aa C\u00fapula da Coaliza\u00e7\u00e3o Global para Alimenta\u00e7\u00e3o Escolar, realizada em Fortaleza, com a presen\u00e7a de representantes de mais de 80 pa\u00edses. O ato [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":140314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[4753,68,1235,2685,5391,87305,18417,87306,18416,73,24536],"class_list":["post-140313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-alimentacao-saudavel","tag-brasil","tag-ceara","tag-escolas-particulares","tag-escolas-publicas","tag-eumano-de-freitas","tag-merenda-escolar","tag-nutricao-infantil","tag-pnae","tag-saude","tag-ultraprocessados","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027<\/title>\n<meta name=\"description\" content=\"Nova lei no Cear\u00e1 pro\u00edbe alimentos ultraprocessados na merenda escolar at\u00e9 2027, em escolas p\u00fablicas e particulares.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/folhadoleste.com.br\/en\/ceara-proibe-ultraprocessados-merenda-escolar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027\" \/>\n<meta property=\"og:description\" content=\"Nova lei no Cear\u00e1 pro\u00edbe alimentos ultraprocessados na merenda escolar at\u00e9 2027, em escolas p\u00fablicas e particulares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/folhadoleste.com.br\/en\/ceara-proibe-ultraprocessados-merenda-escolar\/\" \/>\n<meta property=\"og:site_name\" content=\"Folha do Leste\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/folhadoleste\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-18T20:51:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/09\/Ceara-veta-alimentos-ultraprocessados-na-merenda-escolar-ate-2027-Foto-Antonio-Cruz-AGencia-Brasil.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Enzo Carvalho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FolhadoLesteRJ\" \/>\n<meta name=\"twitter:site\" content=\"@FolhadoLesteRJ\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enzo Carvalho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/ceara-proibe-ultraprocessados-merenda-escolar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/ceara-proibe-ultraprocessados-merenda-escolar\\\/\"},\"author\":{\"name\":\"Enzo Carvalho\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/person\\\/05d8a4b256c9faea581495e6c9be06f2\"},\"headline\":\"Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027\",\"datePublished\":\"2025-09-18T20:51:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/ceara-proibe-ultraprocessados-merenda-escolar\\\/\"},\"wordCount\":246,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/ceara-proibe-ultraprocessados-merenda-escolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Ceara-veta-alimentos-ultraprocessados-na-merenda-escolar-ate-2027-Foto-Antonio-Cruz-AGencia-Brasil.webp\",\"keywords\":[\"alimenta\u00e7\u00e3o saud\u00e1vel\",\"Brasil\",\"Cear\u00e1\",\"escolas particulares\",\"escolas p\u00fablicas\",\"Eumano de Freitas\",\"Merenda Escolar\",\"nutri\u00e7\u00e3o infantil\",\"Pnae\",\"sa\u00fade\",\"ultraprocessados\"],\"articleSection\":[\"Brasil\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/folhadoleste.com.br\\\/ceara-proibe-ultraprocessados-merenda-escolar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/ceara-proibe-ultraprocessados-merenda-escolar\\\/\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/ceara-proibe-ultraprocessados-merenda-escolar\\\/\",\"name\":\"Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/ceara-proibe-ultraprocessados-merenda-escolar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/ceara-proibe-ultraprocessados-merenda-escolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Ceara-veta-alimentos-ultraprocessados-na-merenda-escolar-ate-2027-Foto-Antonio-Cruz-AGencia-Brasil.webp\",\"datePublished\":\"2025-09-18T20:51:59+00:00\",\"description\":\"Nova lei no Cear\u00e1 pro\u00edbe alimentos ultraprocessados na merenda escolar at\u00e9 2027, em escolas p\u00fablicas e particulares.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/ceara-proibe-ultraprocessados-merenda-escolar\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/folhadoleste.com.br\\\/ceara-proibe-ultraprocessados-merenda-escolar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/ceara-proibe-ultraprocessados-merenda-escolar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Ceara-veta-alimentos-ultraprocessados-na-merenda-escolar-ate-2027-Foto-Antonio-Cruz-AGencia-Brasil.webp\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Ceara-veta-alimentos-ultraprocessados-na-merenda-escolar-ate-2027-Foto-Antonio-Cruz-AGencia-Brasil.webp\",\"width\":1170,\"height\":700,\"caption\":\"Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027 | Antonio Cruz\\\/Ag\u00eancia Brasil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/ceara-proibe-ultraprocessados-merenda-escolar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brasil\",\"item\":\"https:\\\/\\\/folhadoleste.com.br\\\/category\\\/brasil\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#website\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/\",\"name\":\"Folha do Leste\",\"description\":\"Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama\",\"publisher\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\"},\"alternateName\":\"FL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/folhadoleste.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#organization\",\"name\":\"Brasil 21 Comunica\u00e7\u00e3o\",\"alternateName\":\"BR21\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/brasil-21-logomarca.avif\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/brasil-21-logomarca.avif\",\"width\":1044,\"height\":1044,\"caption\":\"Brasil 21 Comunica\u00e7\u00e3o\"},\"image\":{\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/folhadoleste\",\"https:\\\/\\\/x.com\\\/FolhadoLesteRJ\",\"https:\\\/\\\/www.instagram.com\\\/folhadoleste\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/#\\\/schema\\\/person\\\/05d8a4b256c9faea581495e6c9be06f2\",\"name\":\"Enzo Carvalho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761\",\"contentUrl\":\"https:\\\/\\\/folhadoleste.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761\",\"caption\":\"Enzo Carvalho\"},\"description\":\"Enzo Carvalho \u00e9 jornalista profissional, com atua\u00e7\u00e3o voltada \u00e0 cobertura de inova\u00e7\u00e3o, tecnologia, cotidiano e esportes. Ex-jogador profissional de e-sports, traz para o jornalismo uma compreens\u00e3o pr\u00e1tica do universo digital, das plataformas tecnol\u00f3gicas e das transforma\u00e7\u00f5es provocadas pela cultura conectada.\",\"url\":\"https:\\\/\\\/folhadoleste.com.br\\\/en\\\/author\\\/enzo-carvalho\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027","description":"Nova lei no Cear\u00e1 pro\u00edbe alimentos ultraprocessados na merenda escolar at\u00e9 2027, em escolas p\u00fablicas e particulares.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/folhadoleste.com.br\/en\/ceara-proibe-ultraprocessados-merenda-escolar\/","og_locale":"en_US","og_type":"article","og_title":"Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027","og_description":"Nova lei no Cear\u00e1 pro\u00edbe alimentos ultraprocessados na merenda escolar at\u00e9 2027, em escolas p\u00fablicas e particulares.","og_url":"https:\/\/folhadoleste.com.br\/en\/ceara-proibe-ultraprocessados-merenda-escolar\/","og_site_name":"Folha do Leste","article_publisher":"https:\/\/www.facebook.com\/folhadoleste","article_published_time":"2025-09-18T20:51:59+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/09\/Ceara-veta-alimentos-ultraprocessados-na-merenda-escolar-ate-2027-Foto-Antonio-Cruz-AGencia-Brasil.webp","type":"image\/webp"}],"author":"Enzo Carvalho","twitter_card":"summary_large_image","twitter_creator":"@FolhadoLesteRJ","twitter_site":"@FolhadoLesteRJ","twitter_misc":{"Written by":"Enzo Carvalho","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/folhadoleste.com.br\/ceara-proibe-ultraprocessados-merenda-escolar\/#article","isPartOf":{"@id":"https:\/\/folhadoleste.com.br\/ceara-proibe-ultraprocessados-merenda-escolar\/"},"author":{"name":"Enzo Carvalho","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/person\/05d8a4b256c9faea581495e6c9be06f2"},"headline":"Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027","datePublished":"2025-09-18T20:51:59+00:00","mainEntityOfPage":{"@id":"https:\/\/folhadoleste.com.br\/ceara-proibe-ultraprocessados-merenda-escolar\/"},"wordCount":246,"commentCount":0,"publisher":{"@id":"https:\/\/folhadoleste.com.br\/#organization"},"image":{"@id":"https:\/\/folhadoleste.com.br\/ceara-proibe-ultraprocessados-merenda-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/09\/Ceara-veta-alimentos-ultraprocessados-na-merenda-escolar-ate-2027-Foto-Antonio-Cruz-AGencia-Brasil.webp","keywords":["alimenta\u00e7\u00e3o saud\u00e1vel","Brasil","Cear\u00e1","escolas particulares","escolas p\u00fablicas","Eumano de Freitas","Merenda Escolar","nutri\u00e7\u00e3o infantil","Pnae","sa\u00fade","ultraprocessados"],"articleSection":["Brasil"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/folhadoleste.com.br\/ceara-proibe-ultraprocessados-merenda-escolar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/folhadoleste.com.br\/ceara-proibe-ultraprocessados-merenda-escolar\/","url":"https:\/\/folhadoleste.com.br\/ceara-proibe-ultraprocessados-merenda-escolar\/","name":"Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027","isPartOf":{"@id":"https:\/\/folhadoleste.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/folhadoleste.com.br\/ceara-proibe-ultraprocessados-merenda-escolar\/#primaryimage"},"image":{"@id":"https:\/\/folhadoleste.com.br\/ceara-proibe-ultraprocessados-merenda-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/09\/Ceara-veta-alimentos-ultraprocessados-na-merenda-escolar-ate-2027-Foto-Antonio-Cruz-AGencia-Brasil.webp","datePublished":"2025-09-18T20:51:59+00:00","description":"Nova lei no Cear\u00e1 pro\u00edbe alimentos ultraprocessados na merenda escolar at\u00e9 2027, em escolas p\u00fablicas e particulares.","breadcrumb":{"@id":"https:\/\/folhadoleste.com.br\/ceara-proibe-ultraprocessados-merenda-escolar\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/folhadoleste.com.br\/ceara-proibe-ultraprocessados-merenda-escolar\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/ceara-proibe-ultraprocessados-merenda-escolar\/#primaryimage","url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/09\/Ceara-veta-alimentos-ultraprocessados-na-merenda-escolar-ate-2027-Foto-Antonio-Cruz-AGencia-Brasil.webp","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/09\/Ceara-veta-alimentos-ultraprocessados-na-merenda-escolar-ate-2027-Foto-Antonio-Cruz-AGencia-Brasil.webp","width":1170,"height":700,"caption":"Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027 | Antonio Cruz\/Ag\u00eancia Brasil"},{"@type":"BreadcrumbList","@id":"https:\/\/folhadoleste.com.br\/ceara-proibe-ultraprocessados-merenda-escolar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/folhadoleste.com.br\/"},{"@type":"ListItem","position":2,"name":"Brasil","item":"https:\/\/folhadoleste.com.br\/category\/brasil\/"},{"@type":"ListItem","position":3,"name":"Cear\u00e1 veta alimentos ultraprocessados na merenda escolar at\u00e9 2027"}]},{"@type":"WebSite","@id":"https:\/\/folhadoleste.com.br\/#website","url":"https:\/\/folhadoleste.com.br\/","name":"Folha do Leste","description":"Portal de Not\u00edcias com \u00eanfase em Niter\u00f3i, criando conte\u00fados desde a capital Rio de Janeiro, com olhar para o Leste Fluminense e suas cidades como S\u00e3o Gon\u00e7alo, Itabora\u00ed, Rio Bonito, Maric\u00e1, Saquarema e Araruama","publisher":{"@id":"https:\/\/folhadoleste.com.br\/#organization"},"alternateName":"FL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/folhadoleste.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/folhadoleste.com.br\/#organization","name":"Brasil 21 Comunica\u00e7\u00e3o","alternateName":"BR21","url":"https:\/\/folhadoleste.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/12\/brasil-21-logomarca.avif","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/uploads\/2025\/12\/brasil-21-logomarca.avif","width":1044,"height":1044,"caption":"Brasil 21 Comunica\u00e7\u00e3o"},"image":{"@id":"https:\/\/folhadoleste.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/folhadoleste","https:\/\/x.com\/FolhadoLesteRJ","https:\/\/www.instagram.com\/folhadoleste\/"]},{"@type":"Person","@id":"https:\/\/folhadoleste.com.br\/#\/schema\/person\/05d8a4b256c9faea581495e6c9be06f2","name":"Enzo Carvalho","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761","url":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761","contentUrl":"https:\/\/folhadoleste.com.br\/wp-content\/litespeed\/avatar\/3fe471b6df482b28961bb8e87cd40a81.jpg?ver=1778370761","caption":"Enzo Carvalho"},"description":"Enzo Carvalho \u00e9 jornalista profissional, com atua\u00e7\u00e3o voltada \u00e0 cobertura de inova\u00e7\u00e3o, tecnologia, cotidiano e esportes. Ex-jogador profissional de e-sports, traz para o jornalismo uma compreens\u00e3o pr\u00e1tica do universo digital, das plataformas tecnol\u00f3gicas e das transforma\u00e7\u00f5es provocadas pela cultura conectada.","url":"https:\/\/folhadoleste.com.br\/en\/author\/enzo-carvalho\/"}]}},"_links":{"self":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/140313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/comments?post=140313"}],"version-history":[{"count":1,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/140313\/revisions"}],"predecessor-version":[{"id":140315,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/posts\/140313\/revisions\/140315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/media\/140314"}],"wp:attachment":[{"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/media?parent=140313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/categories?post=140313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhadoleste.com.br\/en\/wp-json\/wp\/v2\/tags?post=140313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}